{"id":197,"count":7,"description":"","link":"https:\/\/www.protagonist.nl\/blog\/blog\/tag\/website\/","name":"website","slug":"website","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>website Archieven - Protagonist<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.protagonist.nl\/blog\/tag\/website\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"website Archieven - Protagonist\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.protagonist.nl\/blog\/tag\/website\/\" \/>\n<meta property=\"og:site_name\" content=\"Protagonist\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/tag\\\/website\\\/\",\"url\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/tag\\\/website\\\/\",\"name\":\"website Archieven - Protagonist\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/\",\"name\":\"Protagonist\",\"description\":\"Protagonist blog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.protagonist.nl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"website Archieven - Protagonist","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.protagonist.nl\/blog\/tag\/website\/","og_locale":"en_US","og_type":"article","og_title":"website Archieven - Protagonist","og_url":"https:\/\/www.protagonist.nl\/blog\/tag\/website\/","og_site_name":"Protagonist","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.protagonist.nl\/blog\/tag\/website\/","url":"https:\/\/www.protagonist.nl\/blog\/tag\/website\/","name":"website Archieven - Protagonist","isPartOf":{"@id":"https:\/\/www.protagonist.nl\/blog\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/www.protagonist.nl\/blog\/#website","url":"https:\/\/www.protagonist.nl\/blog\/","name":"Protagonist","description":"Protagonist blog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.protagonist.nl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/www.protagonist.nl\/blog\/wp-json\/wp\/v2\/tags\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protagonist.nl\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.protagonist.nl\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.protagonist.nl\/blog\/wp-json\/wp\/v2\/posts?tags=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}